{"id":6099,"date":"2026-04-30T11:01:49","date_gmt":"2026-04-30T08:01:49","guid":{"rendered":"https:\/\/www.withsecure.com\/about-us\/company-contacts-offices\/"},"modified":"2026-05-28T10:17:42","modified_gmt":"2026-05-28T09:17:42","slug":"yhteystiedot","status":"publish","type":"page","link":"https:\/\/www.withsecure.com\/fi\/tietoa-meista\/yhteystiedot\/","title":{"rendered":"Yhteystiedot"},"content":{"rendered":"<section\n    class=\"wp-block-one-column-block edwp-block js-wp-block-one-column-block wp-block-one-column-block--content-1 layout--spacing-xxxxl-top layout--spacing-xl-bottom\"\n    >\n    <div class=\"wp-block-one-column-block__container\">\n                                                                                                                            <div class=\"wp-component-content wp-component-content--default wp-block-one-column-block__content fade-in\">\n            <h1 class=\"wp-component-heading text--h2 wp-component-content__title\">\n    Ota <span class=\"blue-text\">yhteytt\u00e4. <\/span><\/h1>                    <div class=\"wp-component-content__inner\">\n                                    <div class=\"wp-component-content__content wysiwyg\">\n                        <div class=\"wp-component-paragraph \">\n    <p class=\"text--p-medium\">Olipa kyseess\u00e4 kysymys, kumppanuus tai h\u00e4t\u00e4tilanne. Olemme t\u00e4\u00e4ll\u00e4.<\/p>\n<\/div>\n                    <\/div>\n                                                            <\/div>\n                <\/div>                                                                                <\/div>\n<\/section>\n\n\n<section\n    class=\"wp-block-one-column-block edwp-block js-wp-block-one-column-block wp-block-one-column-block--content-1 layout--spacing-xxxl-bottom\"\n    >\n    <div class=\"wp-block-one-column-block__container\">\n                                                                                                                                    <div class=\"wp-component-image__wrapper wp-block-one-column-block__image fade-in\">\n                    <figure class=\"wp-component-image__figure\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2026\/06\/WithSecure_good-partnership.jpg.webp\" class=\"wp-component-image\n                            wp-component-image--desktop\n                            wp-component-image--mobile\n                            wp-component-image--ratio-content-25-1 wp-component-image--fit-cover\" alt=\"\" srcset=\"https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2026\/06\/WithSecure_good-partnership.jpg.webp 1200w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2026\/06\/WithSecure_good-partnership-300x200.jpg.webp 300w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2026\/06\/WithSecure_good-partnership-1024x683.jpg.webp 1024w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2026\/06\/WithSecure_good-partnership-768x512.jpg.webp 768w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2026\/06\/WithSecure_good-partnership-447x298.jpg.webp 447w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2026\/06\/WithSecure_good-partnership-219x146.jpg.webp 219w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>                                                                <figcaption class=\"wp-component-image__caption\n                            wp-component-image__caption--desktop\n                            wp-component-image__caption--mobile\"\n                        >\n                            Woman and man shaking hands                        <\/figcaption>\n                                <\/figure>\n                    <\/div>\n                                                                                <\/div>\n<\/section>\n\n\n<section\n    class=\"wp-block-cards edwp-block wp-block-cards--col-3 layout--spacing-xxxl-top layout--spacing-xxxl-bottom\"\n    >\n    <div class=\"wp-block-cards__container\">\n        <div class=\"wp-component-content wp-component-content--default wp-block-cards__content\">\n            <h2 class=\"wp-component-heading text--h2 wp-component-content__title\">\n    Tapaa <span class=\"blue-text\">WithSecuren tiimit.<\/span><\/h2>                    <div class=\"wp-component-content__inner\">\n                                    <div class=\"wp-component-content__content wysiwyg\">\n                        <div class=\"wp-component-paragraph \">\n    <p>Tarvitsetpa myyntitukea, teknist\u00e4 apua tai haluat tutkia kumppanuutta, meill\u00e4 on ihmiset valmiina keskustelemaan. Valitse tiimi, joka sopii tarpeisiisi.<\/p>\n<\/div>\n                    <\/div>\n                                                            <\/div>\n                <\/div>                    <div class=\"wp-block-cards__box\">\n                                            <div class=\"wp-block-cards__cards row-load\">\n                    <article class=\"wp-component-card wp-block-cards__card wp-component-card--style-default\">\n        <div class=\"wp-component-card__content\">\n                    <div class=\"wp-component-card__icon-wrapper\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"77\" src=\"https:\/\/www.withsecure.com\/wp-content\/uploads\/2025\/11\/icon-response.svg\" class=\"wp-component-card__icon\" alt=\"\" \/>            <\/div>\n                        <div>\n                                    <h2                            class=\"wp-component-card__title\"\n            >\n                Tarvitsetko v\u00e4lit\u00f6nt\u00e4 apua tietoturvapoikkeamaan?        <\/h2>\n                    <\/div>\n                            <p class=\"wp-component-card__description\">\n                Ota yhteytt\u00e4 incident response -tiimiimme<br \/>\r\nSuomi: +358 9 4245 0223<br \/>\r\nIso-Britannia: +44 333 311 0014<br \/>\r\ncir@withsecure.com            <\/p>\n                    <\/div>\n<\/article><article class=\"wp-component-card wp-block-cards__card wp-component-card--style-default\">\n        <div class=\"wp-component-card__content\">\n                    <div class=\"wp-component-card__icon-wrapper\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"77\" src=\"https:\/\/www.withsecure.com\/wp-content\/uploads\/2025\/11\/icon-Support.svg\" class=\"wp-component-card__icon\" alt=\"\" \/>            <\/div>\n                        <div>\n                                    <h2                            class=\"wp-component-card__title\"\n            >\n                Tukea silloin, kun tarvitset sit\u00e4        <\/h2>\n                    <\/div>\n                            <p class=\"wp-component-card__description\">\n                Tekninen tukitiimimme on tavoitettavissa maanantaista perjantaihin klo 08.00\u201318.00 (EET). Premium-tukiasiakkaat saavat 24\/7-katteen. Vieraile tukiportaalissa tai soita alueesi numeroon.            <\/p>\n                            <div class=\"wp-component-card__button-wrapper\">\n                <a class=\"wp-component-button btn btn--primary btn--small wp-component-card__button\" href=\"https:\/\/support.withsecure.com\/en\/support\/contact-support\/call-support\" target=\"_blank\" rel=\"noopener\">Ota yhteytt\u00e4<\/a>                            <\/div>\n            <\/div>\n<\/article><article class=\"wp-component-card wp-block-cards__card wp-component-card--style-default\">\n        <div class=\"wp-component-card__content\">\n                    <div class=\"wp-component-card__icon-wrapper\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"70\" height=\"77\" src=\"https:\/\/www.withsecure.com\/wp-content\/uploads\/2025\/11\/icon-Awareness.svg\" class=\"wp-component-card__icon\" alt=\"\" \/>            <\/div>\n                        <div>\n                                    <h2                            class=\"wp-component-card__title\"\n            >\n                Lehdist\u00f6- ja mediakyselyt        <\/h2>\n                    <\/div>\n                            <p class=\"wp-component-card__description\">\n                Lehdist\u00f6tiedotteet, haastattelupyynn\u00f6t ja muut mediayhteydenotot: PR@withsecure.com.            <\/p>\n                    <\/div>\n<\/article>                <\/div>\n                                        <\/div>\n                            <\/div>\n<\/section>\n\n\n<section\n    class=\"wp-block-one-column-block edwp-block js-wp-block-one-column-block wp-block-one-column-block--content-1 layout--spacing-xxxl-top layout--spacing-xxxl-bottom\"\n     id='offices'>\n    <div class=\"wp-block-one-column-block__container\">\n                                                                                                                            <div class=\"wp-component-content wp-component-content--default wp-block-one-column-block__content fade-in\">\n            <h2 class=\"wp-component-heading text--h2 wp-component-content__title\">\n    Olemme aina t\u00e4\u00e4ll\u00e4 <span class=\"blue-text\">sinua varten.<\/span><\/h2>                    <div class=\"wp-component-content__inner\">\n                                    <div class=\"wp-component-content__content wysiwyg\">\n                        <div class=\"wp-component-paragraph \">\n    <p>T\u00e4\u00e4ll\u00e4 ahkeroimme tietoturvan parissa.<\/p>\n<\/div>\n                    <\/div>\n                                                            <\/div>\n                <\/div>                                                                            <div class=\"wp-component-image__wrapper wp-block-one-column-block__image fade-in\">\n                    <figure class=\"wp-component-image__figure\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"784\" src=\"https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2025\/11\/location-map.png.webp\" class=\"wp-component-image\n                            wp-component-image--desktop\n                            wp-component-image--mobile\n                            wp-component-image--ratio-full wp-component-image--fit-cover\" alt=\"\" srcset=\"https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2025\/11\/location-map.png.webp 1600w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2025\/11\/location-map-300x147.png.webp 300w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2025\/11\/location-map-1024x502.png.webp 1024w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2025\/11\/location-map-768x376.png.webp 768w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2025\/11\/location-map-1536x753.png.webp 1536w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2025\/11\/location-map-447x219.png.webp 447w, https:\/\/www.withsecure.com\/wp-content\/smush-webp\/2025\/11\/location-map-298x146.png.webp 298w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/>                                                    <\/figure>\n                    <\/div>\n                                                                                <\/div>\n<\/section>\n\n\n<section\n    class=\"wp-block-location-cards edwp-block js-wp-block-location-cards layout--spacing-m-bottom\"\n    >\n    <div class=\"wp-block-location-cards__container row-load\">\n                    <div class=\"wp-block-location-cards__card wp-block-location-cards__card--two-offices\">\n                                    <h3 class=\"wp-block-location-cards__title\">Suomi<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Helsinki (P\u00e4\u00e4konttori)<\/h4>\n<p>WithSecure Oyj<br \/>\nV\u00e4limerenkatu 1<br \/>\n00180 Helsinki<br \/>\nFinland<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Oulu<\/h4>\n<p>WithSecure Oyj<br \/>\nSep\u00e4nkatu 20<br \/>\n90100 Oulu<br \/>\nFinland<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Belgia<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Leuven<\/h4>\n<p>WithSecure BV<br \/>\nInterleuvenlaan 62, box 56<br \/>\n3001 Heverlee<br \/>\nLeuven<br \/>\nBelgium<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Tanska<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">K\u00f6\u00f6penhamina<\/h4>\n<p>WithSecure Denmark A\/S<br \/>\nc\/o Bloxhub, Bryghuspladsen 8, (3rd Floor)<br \/>\nDK-1473 Copenhagen<br \/>\nDenmark<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Ranska<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Pariisi<\/h4>\n<p>WithSecure SARL<br \/>\nImmeuble Seine Way<br \/>\nB\u00e2t. G &#8211; 6\u00e8me \u00e9tage<br \/>\n12-14 rue Louis Bl\u00e9riot<br \/>\n92500 RUEIL MALMAISON<br \/>\nFrance<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Saksa<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">M\u00fcnchen<\/h4>\n<p>WithSecure GmbH<br \/>\nKistlerhofstr. 172c<br \/>\n81379 Munich<br \/>\nGermany<\/p>\n<p>+358 9 2520 0700*<\/p>\n<p>Technical Support<br \/>\n+49 (0) 89 38038864<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Japani, Malesia, Singapore<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Tokio<\/h4>\n<p>WithSecure KK<br \/>\nKDX Shinbashi Building 2nd Floor<br \/>\n2-2-9 Shinbashi<br \/>\nMinato-ku<br \/>\nTokyo Japan, 105-0004<\/p>\n<p>+81 3 4578 7700<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Alankomaat<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Rotterdam<\/h4>\n<p>WithSecure B.V.<br \/>\nRegus Rotterdam Airport<br \/>\nRotterdam Airportplein 22<br \/>\n1st floor<br \/>\n3045 AP Rotterdam<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Norja<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Oslo<\/h4>\n<p>WithSecure Norge AS.<br \/>\nOrganisasjonsnr. 913 569 806<\/p>\n<p>c\/o Nytt Foretak AS (registered address)<br \/>\nGrundingen 6<br \/>\n0250 Oslo<br \/>\nNorway<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Puola<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Poznan<\/h4>\n<p>WithSecure Sp. z o. o.<br \/>\npl. W\u0142adys\u0142awa Andersa 5 (14TH Floor)<br \/>\n60-101, Pozna\u0144<br \/>\nPolska<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Ruotsi<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Solna<\/h4>\n<p>CoW Arenastaden, Pyramidv\u00e4gen 7<br \/>\n169756 Solna<br \/>\nSweden<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Iso-Britannia<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Lontoo<\/h4>\n<p>WithSecure Limited<br \/>\nc\/o WeWork, 10 York Road<br \/>\nSE1 7ND London<br \/>\nUnited Kingdom<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                    <div class=\"wp-block-location-cards__card\">\n                                    <h3 class=\"wp-block-location-cards__title\">Yhdysvallat<\/h3>\n                                <div class=\"wp-block-location-cards__offices\">\n                                            <div class=\"wp-block-location-cards__office\">\n                            <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">New York<\/h4>\n<p>WithSecure Inc<br \/>\nc\/o WeWork, 379 West Broadway<br \/>\nNew York City NY 10012<br \/>\nUnited States of America<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                            <div class=\"wp-block-location-cards__accordion\">\n                <div class=\"wp-component-accordion-item row-load wp-component-accordion-item--default wp-component-accordion-item--overlap wp-block-location-cards__accordion-item js-wp-component-accordion-item-group\">\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item wp-component-accordion-item--highlighted\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-0\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-0\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Suomi<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-0\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-0\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Helsinki (P\u00e4\u00e4konttori)<\/h4>\n<p>WithSecure Oyj<br \/>\nV\u00e4limerenkatu 1<br \/>\n00180 Helsinki<br \/>\nFinland<\/p>\n<p>+358 9 2520 0700*<\/p>\n<h4 class=\"text--hxs\">Oulu<\/h4>\n<p>WithSecure Oyj<br \/>\nSep\u00e4nkatu 20<br \/>\n90100 Oulu<br \/>\nFinland<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-1\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-1\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Belgia<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-1\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-1\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Leuven<\/h4>\n<p>WithSecure BV<br \/>\nInterleuvenlaan 62, box 56<br \/>\n3001 Heverlee<br \/>\nLeuven<br \/>\nBelgium<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-2\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-2\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Tanska<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-2\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-2\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">K\u00f6\u00f6penhamina<\/h4>\n<p>WithSecure Denmark A\/S<br \/>\nc\/o Bloxhub, Bryghuspladsen 8, (3rd Floor)<br \/>\nDK-1473 Copenhagen<br \/>\nDenmark<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-3\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-3\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Ranska<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-3\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-3\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Pariisi<\/h4>\n<p>WithSecure SARL<br \/>\nImmeuble Seine Way<br \/>\nB\u00e2t. G &#8211; 6\u00e8me \u00e9tage<br \/>\n12-14 rue Louis Bl\u00e9riot<br \/>\n92500 RUEIL MALMAISON<br \/>\nFrance<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-4\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-4\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Saksa<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-4\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-4\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">M\u00fcnchen<\/h4>\n<p>WithSecure GmbH<br \/>\nKistlerhofstr. 172c<br \/>\n81379 Munich<br \/>\nGermany<\/p>\n<p>+358 9 2520 0700*<\/p>\n<p>Technical Support<br \/>\n+49 (0) 89 38038864<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-5\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-5\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Japani, Malesia, Singapore<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-5\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-5\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Tokio<\/h4>\n<p>WithSecure KK<br \/>\nKDX Shinbashi Building 2nd Floor<br \/>\n2-2-9 Shinbashi<br \/>\nMinato-ku<br \/>\nTokyo Japan, 105-0004<\/p>\n<p>+81 3 4578 7700<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-6\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-6\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Alankomaat<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-6\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-6\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Rotterdam<\/h4>\n<p>WithSecure B.V.<br \/>\nRegus Rotterdam Airport<br \/>\nRotterdam Airportplein 22<br \/>\n1st floor<br \/>\n3045 AP Rotterdam<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-7\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-7\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Norja<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-7\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-7\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Oslo<\/h4>\n<p>WithSecure Norge AS.<br \/>\nOrganisasjonsnr. 913 569 806<\/p>\n<p>c\/o Nytt Foretak AS (registered address)<br \/>\nGrundingen 6<br \/>\n0250 Oslo<br \/>\nNorway<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-8\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-8\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Puola<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-8\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-8\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Poznan<\/h4>\n<p>WithSecure Sp. z o. o.<br \/>\npl. W\u0142adys\u0142awa Andersa 5 (14TH Floor)<br \/>\n60-101, Pozna\u0144<br \/>\nPolska<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-9\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-9\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Ruotsi<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-9\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-9\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Solna<\/h4>\n<p>CoW Arenastaden, Pyramidv\u00e4gen 7<br \/>\n169756 Solna<br \/>\nSweden<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-10\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-10\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Iso-Britannia<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-10\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-10\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">Lontoo<\/h4>\n<p>WithSecure Limited<br \/>\nc\/o WeWork, 10 York Road<br \/>\nSE1 7ND London<br \/>\nUnited Kingdom<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"wp-component-accordion-item__item js-wp-component-accordion-item-item\">\n                        <button\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-11\"\n                class=\"wp-component-accordion-item__title js-wp-component-accordion-item-title\"\n                type=\"button\"\n                aria-expanded=\"false\"\n                aria-controls=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-11\">\n                <span class=\"wp-component-accordion-item__inner-title\">\n                                                            <span>Yhdysvallat<\/span>\n                <\/span>\n                <div class=\"wp-component-accordion-item__toggle\">\n                    <svg class='edwp-icon edwp-icon--lrg js-icon wp-component-accordion-item__toggle__icon' aria-hidden='true'>\n                <use xlink:href='#chevron'><\/use>\n            <\/svg>                <\/div>\n            <\/button>\n            <div\n                id=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-11\"\n                class=\"wp-component-accordion-item__content js-wp-component-accordion-item-content\"\n                aria-labelledby=\"block_a335b2a42ea0787e8a373c885fa9018d-accordion-summary-11\"\n                role=\"region\">\n                <div class=\"wp-component-accordion-item__content__inner\">\n                    <div class=\"wp-component-accordion-item__content__box\">\n                        <div class=\"wp-component-paragraph wp-component-accordion-item__content-text\">\n    <div class=\"wp-component-paragraph \">\n    <h4 class=\"text--hxs\">New York<\/h4>\n<p>WithSecure Inc<br \/>\nc\/o WeWork, 379 West Broadway<br \/>\nNew York City NY 10012<br \/>\nUnited States of America<\/p>\n<p>+358 9 2520 0700*<\/p>\n<\/div>\n<\/div>\n                                                                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n            <\/div>\n            <\/div>\n<\/section>\n\n\n<section\n    class=\"wp-block-one-column-block edwp-block js-wp-block-one-column-block wp-block-one-column-block--content-1 layout--spacing-xxxl-bottom\"\n    >\n    <div class=\"wp-block-one-column-block__container\">\n                                                                                                                            <div class=\"wp-component-paragraph wp-block-one-column-block__paragraph fade-in\">\n    <p>Puhelumaksut vaihtelevat operaattorista riippuen. Asiakaspalvelu on avoinna ma\u2013pe klo 9.00\u201317.00 (EET\/EEST).<\/p>\n<\/div>\n                                                                                <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":6045,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6099","page","type-page","status-publish","hentry"],"acf":[],"card":"<div class=\"wp-component-card-insight js-card-link wp-component-card-insight--highlighted\">\n    <div class=\"wp-component-card-insight__image-wrapper\">\n        <img width=\"618\" height=\"440\" src=\"https:\/\/www.withsecure.com\/wp-content\/uploads\/2026\/05\/placeholder.jpg\" class=\"wp-component-card-insight__image\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.withsecure.com\/wp-content\/uploads\/2026\/05\/placeholder.jpg 618w, https:\/\/www.withsecure.com\/wp-content\/uploads\/2026\/05\/placeholder-300x214.jpg 300w, https:\/\/www.withsecure.com\/wp-content\/uploads\/2026\/05\/placeholder-447x318.jpg 447w, https:\/\/www.withsecure.com\/wp-content\/uploads\/2026\/05\/placeholder-205x146.jpg 205w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/>                    <p class=\"wp-component-card-insight__content-type\">Sivu<\/p>\n            <\/div>\n    <div class=\"wp-component-card-insight__content\">\n                            <h3 class=\"wp-component-card-insight__title\">Yhteystiedot<\/h3>\n                                                    <div class=\"wp-component-card-insight__button-wrapper\">\n                <a class=\"wp-component-button btn btn--primary btn--dark wp-component-card-insight__button btn--small\" href=\"https:\/\/www.withsecure.com\/fi\/tietoa-meista\/yhteystiedot\/\">Lue lis\u00e4\u00e4<\/a>            <\/div>\n            <\/div>\n<\/div>","_links":{"self":[{"href":"https:\/\/www.withsecure.com\/fi\/wp-json\/wp\/v2\/pages\/6099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.withsecure.com\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.withsecure.com\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.withsecure.com\/fi\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.withsecure.com\/fi\/wp-json\/wp\/v2\/comments?post=6099"}],"version-history":[{"count":7,"href":"https:\/\/www.withsecure.com\/fi\/wp-json\/wp\/v2\/pages\/6099\/revisions"}],"predecessor-version":[{"id":10956,"href":"https:\/\/www.withsecure.com\/fi\/wp-json\/wp\/v2\/pages\/6099\/revisions\/10956"}],"up":[{"embeddable":true,"href":"https:\/\/www.withsecure.com\/fi\/wp-json\/wp\/v2\/pages\/6045"}],"wp:attachment":[{"href":"https:\/\/www.withsecure.com\/fi\/wp-json\/wp\/v2\/media?parent=6099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}